{"id":3942,"date":"2021-02-19T18:19:30","date_gmt":"2021-02-19T16:19:30","guid":{"rendered":"http:\/\/optidigital.com\/?p=3942"},"modified":"2025-05-05T16:46:46","modified_gmt":"2025-05-05T14:46:46","slug":"les-meilleurs-formats-publicitaires-en-2021","status":"publish","type":"post","link":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/","title":{"rendered":"Les meilleurs formats publicitaires en 2021"},"content":{"rendered":"\n<p>Un \u00e9l\u00e9ment qui m\u00e9rite une attention particuli\u00e8re lorsque l\u2019on d\u00e9finit son inventaire publicitaire dans l&rsquo;Ad Server est le choix des formats des annonces. Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur.&nbsp;<\/p>\n\n\n\n<p>Nous avions d\u00e9di\u00e9 <a href=\"http:\/\/optidigital.com\/les-meilleurs-formats-publicitaires-sur-mobile-en-2018\/\" target=\"_blank\" rel=\"noreferrer noopener\">un article<\/a> sur le sujet en 2018. 3 ans plus tard, o\u00f9 en sommes-nous ? Quelles tendances se dessinent pour 2021 ? Comment bien choisir ses formats publicitaires ?&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les tailles les plus en vogue sur desktop et mobile<\/strong><\/h3>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/optidigital.com\/wp-content\/uploads\/2021\/02\/Capture-de\u0301cran-2021-02-25-a\u0300-14.50.52-1024x638.png\" alt=\"\" class=\"wp-image-3990\" style=\"width:444px;height:276px\"\/><\/figure>\n<\/div>\n\n\n<p>D\u2019apr\u00e8s l\u2019<a href=\"https:\/\/www.iab.com\/guidelines\/iab-new-ad-portfolio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Advertising Creative Guidelines<\/a> de l\u2019IAB (Internet Advertising Bureau), le 300&#215;250 pixels occupe la premi\u00e8re place du podium parmi les tailles les plus pl\u00e9biscit\u00e9es sur desktop.&nbsp;<\/p>\n\n\n\n<p>Elle repr\u00e9sente 40% des impressions publicitaires totales et est davantage appr\u00e9ci\u00e9e par l\u2019utilisateur car moins intrusive que les formats de grandes tailles situ\u00e9s sur la partie sup\u00e9rieure des pages Web : Megabanner 728&#215;90, Billboard 970&#215;250 ou encore Habillage qui encadre litt\u00e9ralement le site internet.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Souvent positionn\u00e9 au-dessus de la ligne de flottaison, ce format peut aussi se glisser en c\u0153ur d\u2019article, emplacement \u00e0 forte valeur ajout\u00e9e pour la mon\u00e9tisation des m\u00e9dias puisque c\u2019est l\u00e0 o\u00f9 l\u2019internaute concentre son attention. Chez Opti Digital, nous recommandons cet emplacement strat\u00e9gique en c\u0153ur d\u2019article et avons d\u00e9velopp\u00e9 une technologie d\u2019insertion dynamique des annonces afin d\u2019exploiter tout le potentiel publicitaire d\u2019un site Web.&nbsp;<\/p>\n\n\n\n<p>Lire : <a href=\"http:\/\/optidigital.com\/pourquoi-faut-il-accorder-de-limportance-aux-emplacements-publicitaires-dans-sa-strategie-de-monetisation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pourquoi faut-il accorder de l\u2019importance aux emplacements publicitaires dans sa strat\u00e9gie de mon\u00e9tisation ?<\/a><\/p>\n\n\n\n<p>Sur mobile, en revanche, c\u2019est la taille 320&#215;50 qui est la plus populaire autant sur web que sur application puisqu\u2019elle couvre 12% des impressions publicitaires totales selon l\u2019IAB. Avec l\u2019essor des applications mobiles et la mont\u00e9e en puissance de la tendance mobile first, c\u2019est un format \u00e0 ne pas omettre cette ann\u00e9e pour maximiser ses revenus.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Capter l\u2019attention de l&rsquo;utilisateur avec les annonces interstitielles<\/strong><\/h3>\n\n\n\n<p>D\u2019apr\u00e8s la d\u00e9finition de Google, une publicit\u00e9 interstitielle est une annonce au format 320&#215;480 \u201c<em>qui s\u2019affiche en plein \u00e9cran sur mobile \u00e0 des moments de transitions naturels, par exemple \u00e0 un changement de page, au lancement d\u2019une application ou au t\u00e9l\u00e9chargement d\u2019un niveau de jeu<\/em>\u201d.<\/p>\n\n\n\n<p>Ce format a d\u2019abord \u00e9t\u00e9 adopt\u00e9 par Google en 2015 afin de faire interagir le mobinaute avec la publicit\u00e9; pour ensuite \u00eatre p\u00e9nalis\u00e9 par ce dernier, en 2017, car jug\u00e9 intrusif et bloquant pour la navigation de l\u2019utilisateur.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/optidigital.com\/wp-content\/uploads\/2021\/02\/Best-Practice-Google.png\" alt=\"\" class=\"wp-image-3956\" style=\"width:428px;height:262px\"\/><figcaption class=\"wp-element-caption\">Source : <em>Google AdMob &#8211; Instructions relatives \u00e0 l\u2019int\u00e9gration des annonces interstitielles<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Aujourd\u2019hui, il fait son grand retour sur mobile, sous certaines conditions \u00e9tablies par la <a href=\"https:\/\/www.betterads.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Coalition for Better Ads<\/a> dont Google est signataire. Les \u00e9diteurs doivent l\u2019int\u00e9grer avec pr\u00e9caution en respectant <a href=\"https:\/\/support.google.com\/admob\/answer\/6066980?hl=fr&amp;ref_topic=2936214\" target=\"_blank\" rel=\"noreferrer noopener\">ces crit\u00e8res<\/a> :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ne pas inonder les pages d\u2019annonces interstitielles pour ne pas d\u00e9t\u00e9riorer l\u2019exp\u00e9rience utilisateur. Par d\u00e9faut, le capping sur ce format est de 1 par user et par session sur Google Ad Exchange.\u00a0<\/li>\n\n\n\n<li>Ne pas entraver la navigation des utilisateurs avec l\u2019affichage d\u2019une publicit\u00e9 inopportune au risque d\u2019augmenter le nombre de clics accidentels. L&rsquo;annonce ne doit pas occuper l\u2019int\u00e9gralit\u00e9 de l\u2019\u00e9cran et l\u2019internaute doit pouvoir la fermer sans attendre un laps de temps.<\/li>\n<\/ul>\n\n\n\n<p>Pour aider \u00e0 bien les positionner, Google recommande de se poser les questions suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qu\u2019est-ce que l\u2019utilisateur sera en train de faire \u00e0 ce moment-l\u00e0 ?<\/li>\n\n\n\n<li>Sera-t-il surpris de voir appara\u00eetre une annonce interstitielle ? (<em>vu la taille de l\u2019annonce, \u00e7a ne fait aucun doute <\/em>\ud83e\udd13)<\/li>\n\n\n\n<li>Le moment est-il bien choisi pour diffuser l\u2019annonce ?\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Bien plac\u00e9es et utilis\u00e9es \u00e0 bon escient, les publicit\u00e9s interstitielles augmentent fortement la rentabilit\u00e9 des m\u00e9dias et peuvent rapporter beaucoup plus que les banni\u00e8res mobiles classiques.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-174197273423\"\n  style=\"max-width:100%; max-height:100%; width:650px;height:162.5px\" data-hubspot-wrapper-cta-id=\"174197273423\">\n  <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLIWdvEGEX9Prq0El04kFiZnqT3ivlX7a5Xevf6naFtpi%2FBZzlWpwyhJZmkl3UkubMz8bO1VyaptjX005ORMvbpIcvlrSnr3g6fKVFYc2ZJr8AgJ3ExGm76ZydSqmrwQQMpUmtdqcvTZHxPpCDfqsS7F9dOl%2BHEKeymc1tXfHd%2BnZtRVDMYkfhVX7SM9Rtnri3ZwLQ%2BPQrNUoh7ds4eRU5JIzVaqfsPBEyxnQK1Vi8PMGWgRZ0qQ4YUxsi97pT6LfF2wF5NCig%3D%3D&#038;webInteractiveContentId=174197273423&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n    <img decoding=\"async\" alt=\"2-Jul-31-2024-10-28-08-2442-AM\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-174197273423.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n      onerror=\"this.style.display='none'\" \/>\n  <\/a>\n<\/div>\n\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Maintenir une bonne pression publicitaire gr\u00e2ce au Sticky Bottom<\/strong><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft is-resized\"><img decoding=\"async\" src=\"http:\/\/optidigital.com\/wp-content\/uploads\/2021\/02\/Copy-of-12_Large-Sticky-Ad-1.gif\" alt=\"\" class=\"wp-image-3963\" style=\"width:252px;height:252px\"\/><figcaption class=\"wp-element-caption\"><em>Source : Coalition for Better Ads<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Le format Sticky Bottom se positionne automatiquement en pied de page pour y afficher une publicit\u00e9 sans empi\u00e9ter sur le contenu. Les tailles les plus utilis\u00e9es pour ce format sont le leaderboard en 728&#215;90 sur desktop et les banni\u00e8res 320&#215;50 ou 320&#215;100 sur mobile.&nbsp;<\/p>\n\n\n\n<p>Les b\u00e9n\u00e9fices de ce format sont doubles : tant pour l\u2019\u00e9diteur que pour l\u2019annonceur puisqu\u2019il permet d\u2019obtenir une bonne visibilit\u00e9 publicitaire et augmente le temps d\u2019affichage de l\u2019annonce.&nbsp;<\/p>\n\n\n\n<p>Chez Opti Digital, nous recommandons aux \u00e9diteurs que nous accompagnons de mettre en place ce format avec notre technologie de rafraichissement intelligent afin de g\u00e9n\u00e9rer des impressions suppl\u00e9mentaires sur cet emplacement et accro\u00eetre le taux de visibilit\u00e9 au global.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>L\u2019exp\u00e9rience utilisateur au c\u0153ur des pr\u00e9occupations en 2021<\/strong><\/h3>\n\n\n\n<p>Pr\u00e9server une bonne exp\u00e9rience utilisateur sera le fer de lance cette ann\u00e9e pour le r\u00e9f\u00e9rencement naturel. En effet, \u00e0 partir de mai 2021, Google va mesurer les signaux Web essentiels (ou <a href=\"https:\/\/web.dev\/vitals\/\" target=\"_blank\" rel=\"noreferrer noopener\">Core Web Vitals<\/a>) afin de favoriser les sites proposant la meilleure exp\u00e9rience utilisateur &#8211; et, \u00e0 l\u2019inverse, p\u00e9naliser les sites au chargement lent avec des annonces intrusives venant polluer la navigation des utilisateurs.&nbsp;<\/p>\n\n\n\n<p>Une m\u00e9trique qui sera prise en compte dans la mesure des Core Web Vitals est le CLS ou Cumulative Layout Shift, un indicateur cl\u00e9 pour la stabilit\u00e9 de la page. Ce taux mesure la fr\u00e9quence \u00e0 laquelle les internautes subissent des changements de mise en page inattendus : des sauts de contenu li\u00e9s \u00e0 l\u2019apparition d\u2019une publicit\u00e9 au chargement de la page. Pour ne pas alterner l\u2019UX et \u00eatre p\u00e9nalis\u00e9 par Google, le score CLS doit \u00eatre au plus proche de 0 (maximum 0,1).&nbsp;<\/p>\n\n\n\n<p>Chez Opti Digital, nous recommandons de ne pas configurer qu\u2019une seule taille dans un emplacement mais d\u2019en mettre plusieurs en concurrence les unes contre les autres tout en s\u2019assurant d\u2019un bon score CLS en parall\u00e8le.&nbsp;<\/p>\n\n\n\n<p>N\u2019h\u00e9sitez pas \u00e0 vous faire accompagner par nos experts pour \u00eatre s\u00fbr.e de faire les bons choix pour votre inventaire publicitaire et votre SEO.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un \u00e9l\u00e9ment qui m\u00e9rite une attention particuli\u00e8re lorsque l\u2019on d\u00e9finit son inventaire publicitaire dans l&rsquo;Ad Server est le choix des formats des annonces. Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur.&nbsp; Nous avions &#8230; <a title=\"Les meilleurs formats publicitaires en 2021\" class=\"read-more\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/\" aria-label=\"En savoir plus sur Les meilleurs formats publicitaires en 2021\">Lire la suite<\/a><\/p>\n","protected":false},"author":9,"featured_media":24091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[394,611,401],"tags":[],"class_list":["post-3942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-industrie","category-publicite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les meilleurs formats publicitaires en 2021 - Optidigital<\/title>\n<meta name=\"description\" content=\"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les meilleurs formats publicitaires en 2021 - Optidigital\" \/>\n<meta property=\"og:description\" content=\"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Optidigital\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T16:19:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T14:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"chloecouannet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"chloecouannet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/\"},\"author\":{\"name\":\"chloecouannet\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d828e6c2a78b1062b8989b896189978\"},\"headline\":\"Les meilleurs formats publicitaires en 2021\",\"datePublished\":\"2021-02-19T16:19:30+00:00\",\"dateModified\":\"2025-05-05T14:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/\"},\"wordCount\":1044,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/the_best_advertising_formats_in_2021_1x.webp\",\"articleSection\":[\"Blog\",\"Industrie\",\"Publicit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/\",\"name\":\"Les meilleurs formats publicitaires en 2021 - Optidigital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/the_best_advertising_formats_in_2021_1x.webp\",\"datePublished\":\"2021-02-19T16:19:30+00:00\",\"dateModified\":\"2025-05-05T14:46:46+00:00\",\"description\":\"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/the_best_advertising_formats_in_2021_1x.webp\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/the_best_advertising_formats_in_2021_1x.webp\",\"width\":600,\"height\":400,\"caption\":\"The best advertising formats in 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/les-meilleurs-formats-publicitaires-en-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les meilleurs formats publicitaires en 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"name\":\"Optidigital\",\"description\":\"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.\",\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\",\"name\":\"Optidigital\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"width\":169,\"height\":64,\"caption\":\"Optidigital\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/3d828e6c2a78b1062b8989b896189978\",\"name\":\"chloecouannet\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/author\\\/chloecouannet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les meilleurs formats publicitaires en 2021 - Optidigital","description":"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Les meilleurs formats publicitaires en 2021 - Optidigital","og_description":"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.","og_url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/","og_site_name":"Optidigital","article_published_time":"2021-02-19T16:19:30+00:00","article_modified_time":"2025-05-05T14:46:46+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","type":"image\/webp"}],"author":"chloecouannet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"chloecouannet","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#article","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/"},"author":{"name":"chloecouannet","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/3d828e6c2a78b1062b8989b896189978"},"headline":"Les meilleurs formats publicitaires en 2021","datePublished":"2021-02-19T16:19:30+00:00","dateModified":"2025-05-05T14:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/"},"wordCount":1044,"commentCount":0,"publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","articleSection":["Blog","Industrie","Publicit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/","url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/","name":"Les meilleurs formats publicitaires en 2021 - Optidigital","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#primaryimage"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","datePublished":"2021-02-19T16:19:30+00:00","dateModified":"2025-05-05T14:46:46+00:00","description":"Bien choisir les tailles des publicit\u00e9s et leurs emplacements sur les pages est essentiel pour faire grimper les taux de visibilit\u00e9 et les RPM page tout en pr\u00e9servant l\u2019exp\u00e9rience utilisateur. D\u00e9couvrez quels sont les meilleurs formats publicitaires en 2021.","breadcrumb":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#primaryimage","url":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","width":600,"height":400,"caption":"The best advertising formats in 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/les-meilleurs-formats-publicitaires-en-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optidigital.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les meilleurs formats publicitaires en 2021"}]},{"@type":"WebSite","@id":"https:\/\/optidigital.com\/fr\/#website","url":"https:\/\/optidigital.com\/fr\/","name":"Optidigital","description":"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.","publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optidigital.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optidigital.com\/fr\/#organization","name":"Optidigital","url":"https:\/\/optidigital.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","width":169,"height":64,"caption":"Optidigital"},"image":{"@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/3d828e6c2a78b1062b8989b896189978","name":"chloecouannet","url":"https:\/\/optidigital.com\/fr\/author\/chloecouannet\/"}]}},"featured_image_url":"https:\/\/optidigital.com\/wp-content\/uploads\/the_best_advertising_formats_in_2021_1x.webp","_links":{"self":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/3942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/comments?post=3942"}],"version-history":[{"count":1,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/3942\/revisions"}],"predecessor-version":[{"id":23633,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/3942\/revisions\/23633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media\/24091"}],"wp:attachment":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media?parent=3942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/categories?post=3942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/tags?post=3942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}