{"id":28784,"date":"2024-11-20T10:56:35","date_gmt":"2024-11-20T09:56:35","guid":{"rendered":"https:\/\/optidigital.com\/?p=28784"},"modified":"2026-05-08T11:33:11","modified_gmt":"2026-05-08T09:33:11","slug":"le-header-bidding-face-au-waterfall","status":"publish","type":"post","link":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/","title":{"rendered":"Le Header Bidding face au Waterfall"},"content":{"rendered":"\n<p><strong><strong>Le Header Bidding est devenu un outil indispensable pour les \u00e9diteurs dans l&rsquo;\u00e9cosyst\u00e8me innovant du programmatique, gr\u00e2ce \u00e0 sa capacit\u00e9 \u00e0 maximiser le yield et \u00e0 instaurer une r\u00e9elle comp\u00e9tition sur l&rsquo;inventaire publicitaire. Mais avant l&rsquo;av\u00e8nement du Header Bidding, c&rsquo;est le Waterfall qui dominait le paysage. Dans ce deuxi\u00e8me volet de notre s\u00e9rie, nous explorerons l&rsquo;histoire du programmatique pour comprendre les bases qui ont men\u00e9 au d\u00e9veloppement de ces techniques. Nous comparerons ensuite le Header Bidding face au Waterfall pour identifier les forces et faiblesses de chacun.<\/strong><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;Histoire de la Publicit\u00e9 Programmatique<\/h2>\n\n\n\n<p>Les fondements de la publicit\u00e9 programmatique remontent \u00e0 la fin des ann\u00e9es 90 avec des deals directs et manuels entre \u00e9diteurs et annonceurs. \u00c0 l&rsquo;\u00e9poque, les \u00e9diteurs vendaient leur inventaire premium en direct selon des tarifs fixes, tandis que l&rsquo;inventaire non-vendu \u00e9tait c\u00e9d\u00e9 aux r\u00e9seaux publicitaires \u00e0 des tarifs inf\u00e9rieurs. Ce processus reposait enti\u00e8rement sur les \u00e9quipes commerciales et les ordres d&rsquo;insertion manuels, ce qui prenait beaucoup de temps et d&rsquo;effort.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; width: 100%;\">\n  <div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-192302707121\"\n    style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"192302707121\">\n    <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLLsGUaCilYgQ9oUlFQcADRjMc%2BaamcbQwn%2BtbstzUNnHPCkBqUiVZnDBAAsXndQKSvB6cKOujurJEG7xF92%2BjjUqJkCpghYwPBsZT%2B6QK8B2f9pZWygV%2FqPS1rJD801xC9qA%2F8yMvH0RgILCJ1ozBCy0DytMdHdsovjyYWLTnUKvBTGpzCTJATmaI3m10XSZuswa0PI6lLvi1C6Gq6%2Bu%2BGIneMroTDLVielyaNSDhICCA%2FL1QqbMpUo8juAPMjQy0hrHXM%2BcZJyw5MCv3uno9hiXaPf%2B4P2KDpPxAARZp0WPQl8eAgMChYO4SuPvWfnpow%3D&#038;webInteractiveContentId=192302707121&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n      <img decoding=\"async\" alt=\"El Plural\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-192302707121.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n        onerror=\"this.style.display='none'\" \/>\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L&rsquo;introduction des ad exchanges a marqu\u00e9 la premi\u00e8re \u00e9tape vers la publicit\u00e9 programmatique. Contrairement \u00e0 l&rsquo;approche un \u00e0 un des deals directs, les ad exchanges ont cr\u00e9\u00e9 une marketplace num\u00e9rique o\u00f9 tous les participants pouvaient acheter et vendre entre eux. Cependant, ces premiers exchanges manquaient encore de capacit\u00e9s de temps r\u00e9el et de ciblage sophistiqu\u00e9.<\/p>\n\n\n\n<p><a href=\"https:\/\/optidigital.com\/resources\/blog\/programmatic-advertising-guide\/\">Le programmatique tel que nous le connaissons aujourd&rsquo;hui<\/a> a v\u00e9ritablement pris son essor au milieu des ann\u00e9es 2000 avec l&rsquo;introduction du Real-Time Bidding (RTB). Le RTB a permis aux \u00e9diteurs de maximiser leur eCPM par impression, particuli\u00e8rement sur les audiences \u00e0 forte valeur ajout\u00e9e ou lors des pics de trafic, les annonceurs \u00e9tant pr\u00eats \u00e0 ench\u00e9rir agressivement pour des placements sp\u00e9cifiques. Les \u00e9diteurs ont ainsi pu g\u00e9n\u00e9rer un meilleur revenu sur chaque impression individuelle au lieu de d\u00e9pendre des achats en volume \u00e0 bas prix issus des deals directs.<\/p>\n\n\n\n<p>\u00c0 mesure que le RTB s&rsquo;est impos\u00e9, les \u00e9diteurs ont d\u00fb trouver un moyen de g\u00e9rer efficacement leurs multiples sources de demande. C\u2019est l\u2019une des raisons qui a men\u00e9 au d\u00e9veloppement du waterfall bidding aux alentours de 2009. Gr\u00e2ce \u00e0 cette technique de cascade, les \u00e9diteurs ont pu prioriser leurs partenaires de demande, g\u00e9n\u00e9ralement sur la base de leurs performances historiques. Concr\u00e8tement, l&rsquo;ad network offrant l&rsquo;eCPM le plus \u00e9lev\u00e9 \u00e9tait appel\u00e9 en premier, suivi par le suivant dans la pile, et ainsi de suite.<\/p>\n\n\n\n<p>Enfin, une derni\u00e8re avanc\u00e9e majeure a eu lieu avec l&rsquo;apparition du header bidding. Introduit vers 2014, le header bidding a permis aux \u00e9diteurs de solliciter des ench\u00e8res aupr\u00e8s de plusieurs partenaires de demande simultan\u00e9ment avant m\u00eame d&rsquo;appeler leur ad server. Cette innovation a permis de lever les contraintes s\u00e9quentielles propres au waterfall et d&rsquo;augmenter significativement le revenu publicitaire global.<\/p>\n\n\n\n<p>Maintenant que nous avons une vision d&rsquo;ensemble de l&rsquo;historique de ces processus, examinons plus en d\u00e9tail le fonctionnement du waterfall bidding.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Waterfall Bidding<\/h2>\n\n\n\n<p>Aux alentours de 2009, les \u00e9diteurs ont d\u00fb faire face \u00e0 deux besoins distincts : g\u00e9rer efficacement de multiples sources de demande et \u00e9couler l&rsquo;inventaire remnant qui n&rsquo;\u00e9tait pas vendu via des deals directs. C&rsquo;est ainsi qu&rsquo;est n\u00e9 le waterfall bidding (\u00e9galement connu sous le nom de daisy-chaining ou waterfall tag).<\/p>\n\n\n\n<p>Ce processus suit une structure hi\u00e9rarchique o\u00f9 les impressions publicitaires sont propos\u00e9es de mani\u00e8re s\u00e9quentielle aux sources de demande selon des niveaux de priorit\u00e9 pr\u00e9d\u00e9finis, cr\u00e9ant un effet de cascade. Ces sources de demande sont g\u00e9n\u00e9ralement class\u00e9es soit par leur taille, soit par le yield historique moyen qu&rsquo;elles ont g\u00e9n\u00e9r\u00e9 pour l&rsquo;\u00e9diteur. Cela signifie qu&rsquo;un ad network ayant vendu de l&rsquo;inventaire premium par le pass\u00e9 (\u00e0 un prix \u00e9lev\u00e9) aura la priorit\u00e9 sur les prochaines impressions du m\u00eame \u00e9diteur. G\u00e9n\u00e9ralement, les \u00e9diteurs abaissent leur price floor \u00e0 chaque \u00e9tape de la cascade, dans l&rsquo;espoir de trouver l&rsquo;annonce la mieux r\u00e9mun\u00e9r\u00e9e dans le d\u00e9lai le plus court possible.<\/p>\n\n\n\n<p>Dans une configuration de waterfall bidding, le processus se d\u00e9roule de la mani\u00e8re suivante :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Un utilisateur visite une page web contenant un emplacement publicitaire.<\/li>\n\n\n\n<li>Le waterfall bidding s&rsquo;enclenche lorsque l&rsquo;ad server de l&rsquo;\u00e9diteur appelle le premier ad network de la s\u00e9quence.<\/li>\n\n\n\n<li>Si le premier ad network ne peut pas remplir l&#8217;emplacement, il passe la main au r\u00e9seau suivant.<\/li>\n\n\n\n<li>Ce processus se poursuit jusqu&rsquo;\u00e0 ce que l&#8217;emplacement soit rempli ou que toutes les sources de demande soient \u00e9puis\u00e9es.<\/li>\n\n\n\n<li>&lsquo;annonce gagnante est alors diffus\u00e9e \u00e0 l&rsquo;utilisateur.<\/li>\n<\/ol>\n\n\n\n<p>L&rsquo;ensemble du processus prend g\u00e9n\u00e9ralement entre 800 et 1500 millisecondes.<\/p>\n\n\n\n<p>Plusieurs raisons peuvent expliquer pourquoi un ad network n&rsquo;est pas en mesure de remplir un emplacement publicitaire :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le price floor de l&rsquo;\u00e9diteur \u00e9tait peut-\u00eatre plus \u00e9lev\u00e9 que le prix propos\u00e9 par la source de demande.<\/li>\n\n\n\n<li>La source de demande a subi un timeout car elle a mis trop de temps \u00e0 r\u00e9pondre \u00e0 l&rsquo;ad request.<\/li>\n\n\n\n<li>Il se peut qu&rsquo;il n&rsquo;y ait eu aucune publicit\u00e9 pertinente pour l&rsquo;utilisateur ou le site selon les crit\u00e8res de ciblage. Par exemple, le site web peut \u00eatre ax\u00e9 sur le voyage alors que la source de demande n&rsquo;avait que des publicit\u00e9s li\u00e9es au sport. Les ad networks re\u00e7oivent les informations sur le site et l&rsquo;utilisateur via l&rsquo;ad server de l&rsquo;\u00e9diteur, ce qui leur permet de d\u00e9cider si l&rsquo;impression est int\u00e9ressante \u00e0 remplir.<\/li>\n\n\n\n<li>L&rsquo;annonceur achetant via les ad networks peut avoir mis en place un capping d&rsquo;impressions, une strat\u00e9gie courante pour limiter le nombre de fois o\u00f9 ses publicit\u00e9s sont diffus\u00e9es aupr\u00e8s d&rsquo;une m\u00eame personne sur une p\u00e9riode donn\u00e9e.<\/li>\n<\/ul>\n\n\n\n<p>Si aucune des sources de demande n&rsquo;est en mesure de remplir l&rsquo;impression, celle-ci reste invendue, ce qui m\u00e8ne \u00e0 un sc\u00e9nario de passback : la requ\u00eate publicitaire est renvoy\u00e9e vers l&rsquo;ad server par d\u00e9faut de l&rsquo;\u00e9diteur. Ce dernier peut alors diffuser une publicit\u00e9 de repli, comme une auto-promo faisant la promotion de ses propres contenus ou services, ou une annonce d&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral (PSA).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"http:\/\/optidigital.com\/wp-content\/uploads\/2024\/11\/2.jpg\" alt=\"Waterfall bidding process.\" class=\"wp-image-21204\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Avantages du Waterfall Bidding<\/h3>\n\n\n\n<p>Le waterfall bidding a aid\u00e9 les \u00e9diteurs de plusieurs mani\u00e8res :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inventaire Remnant :<\/strong> Le principal avantage du waterfall bidding est qu&rsquo;il permet aux \u00e9diteurs de liquider l&rsquo;inventaire publicitaire invendu qui, autrement, aurait \u00e9t\u00e9 perdu.<\/li>\n\n\n\n<li><strong>Facilit\u00e9 d&rsquo;impl\u00e9mentation :<\/strong> Le waterfalling est assez simple \u00e0 mettre en place et n\u00e9cessite peu de connaissances techniques. Pour que cela fonctionne, la seule configuration requise est l&rsquo;installation d&rsquo;un tag sur un ad network.<\/li>\n\n\n\n<li><strong>Gestion :<\/strong> Le waterfall bidding est relativement facile \u00e0 g\u00e9rer, ce qui en fait une excellente option pour les petits \u00e9diteurs ou ceux ayant des ressources technologiques limit\u00e9es.<\/li>\n\n\n\n<li><strong>Deals Directs :<\/strong> Si un \u00e9diteur entretient des relations privil\u00e9gi\u00e9es avec certains annonceurs ou ad networks, utiliser une configuration en waterfall pour les prioriser peut s&rsquo;av\u00e9rer \u00eatre une strat\u00e9gie pertinente.<\/li>\n<\/ul>\n\n\n\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-172079787379\"\n  style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"172079787379\">\n  <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLJu3MzbfXEUocdO0uoYY3JGhYmYlm1DHmV91VG2CzdfQlJLyXkWe6V9LAXXQMoUB1c%2BFG1AI25bfnDakLdWtCYRG99Cum27T7gT03xDNKz8yV%2BIZnzvxavKtU9DLR5d%2BfBL7OBaSg5g7bwtIc3LkORoIaO%2BqA9oe72E4GXihpCiSND4ayYqpVNdNB7KGL3C77zFon047R%2B1RYtbAjkSHwgIHjofNmC1AhMGCXtQQedG9KM6AbbgM%2F60JQMnpEiiYIEjKtGx4jljuP0%2BVz1jD%2Bo%3D&#038;webInteractiveContentId=172079787379&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n    <img decoding=\"async\" alt=\"Blog Content Banner\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-172079787379.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n      onerror=\"this.style.display='none'\" \/>\n  <\/a>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Limites du Waterfall Bidding<\/h3>\n\n\n\n<p>Mais le waterfall bidding a \u00e9galement apport\u00e9 son lot d&rsquo;obstacles.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Classement :<\/strong> L&rsquo;ordre pr\u00e9d\u00e9fini des sources de demande est souvent d\u00e9termin\u00e9 par leur taille ou par leur yield historique moyen, plut\u00f4t que par le montant qu&rsquo;elles sont pr\u00eates \u00e0 ench\u00e9rir \u00e0 un instant T. Par cons\u00e9quent, le revenu publicitaire n&rsquo;est pas optimis\u00e9.<\/li>\n\n\n\n<li><strong>Perte d&rsquo;opportunit\u00e9 :<\/strong> Si l&rsquo;ench\u00e9risseur le plus offrant se trouve plus bas dans le classement, il n&rsquo;aura jamais l&rsquo;opportunit\u00e9 de soumettre son offre.<\/li>\n\n\n\n<li><strong>Latence :<\/strong> Le fait de faire descendre une impression le long de la cascade jusqu&rsquo;\u00e0 ce qu&rsquo;elle soit achet\u00e9e entra\u00eene des d\u00e9lais de chargement publicitaire (latence).<\/li>\n\n\n\n<li><strong>Valeur de l&rsquo;inventaire :<\/strong> Avec le waterfall bidding, les \u00e9diteurs g\u00e8rent leur inventaire publicitaire non pas sur sa valeur r\u00e9elle, mais sur une estimation th\u00e9orique de ce qu&rsquo;une impression vaut.<\/li>\n<\/ul>\n\n\n\n<p>Ces obstacles emp\u00eachaient les \u00e9diteurs de maximiser leurs revenus publicitaires, impactaient n\u00e9gativement l&rsquo;UX et surchargeaient les \u00e9quipes programmatiques. C&rsquo;est pourquoi le header bidding s&rsquo;est impos\u00e9 comme une progression naturelle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Header Bidding<\/h2>\n\n\n\n<p>Comme nous <a href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/quest-ce-que-le-header-bidding-et-comment-limplementer\/\">l&rsquo;avons vu la semaine derni\u00e8re<\/a>, le header bidding a succ\u00e9d\u00e9 au waterfall bidding en offrant aux \u00e9diteurs une m\u00e9thode de travail bien plus performante.&nbsp;<\/p>\n\n\n\n<p>Le processus du header bidding c\u00f4t\u00e9 client fonctionne de la mani\u00e8re suivante :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Un utilisateur arrive sur un site disposant d&rsquo;un emplacement publicitaire disponible.<\/li>\n\n\n\n<li>Le code situ\u00e9 dans le header du site envoie une requ\u00eate \u00e0 plusieurs partenaires de demande avec des d\u00e9tails sur l&rsquo;utilisateur, la page consult\u00e9e et l&#8217;emplacement publicitaire.<\/li>\n\n\n\n<li>Les partenaires int\u00e9ress\u00e9s par l&#8217;emplacement r\u00e9pondent avec leurs ench\u00e8res.<\/li>\n\n\n\n<li>Ces ench\u00e8res sont collect\u00e9es et transmises \u00e0 l&rsquo;ad server du site.<\/li>\n\n\n\n<li>L&rsquo;ad server analyse les donn\u00e9es des ench\u00e8res pour s\u00e9lectionner la plus \u00e9lev\u00e9e et d\u00e9cider quelle publicit\u00e9 diffuser.<\/li>\n\n\n\n<li>Enfin, la publicit\u00e9 choisie est affich\u00e9e sur le site et l&rsquo;impression est comptabilis\u00e9e.<\/li>\n<\/ol>\n\n\n\n<p>Bien que cela puisse para\u00eetre long, l&rsquo;ensemble du processus est tr\u00e8s rapide : environ 400 \u00e0 800 millisecondes sur un ordinateur de bureau et entre 800 et 1200 millisecondes sur un appareil mobile !<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"http:\/\/optidigital.com\/wp-content\/uploads\/2024\/11\/1-1.jpg\" alt=\"Header Bidding process.\" class=\"wp-image-21202\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Avantages du Header Bidding<\/h3>\n\n\n\n<p>Le header bidding apporte de nombreux avantages aux \u00e9diteurs.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Augmentation des revenus :<\/strong> la concurrence accrue maximise le potentiel de mon\u00e9tisation publicitaire.<\/li>\n\n\n\n<li><strong>Transparence : <\/strong>les \u00e9diteurs peuvent contr\u00f4ler quels partenaires de demande sont autoris\u00e9s \u00e0 ench\u00e9rir sur leur inventaire. Ils peuvent \u00e9galement prioriser certains annonceurs par rapport \u00e0 d&rsquo;autres, et m\u00eame emp\u00eacher certains annonceurs de participer aux ench\u00e8res.<\/li>\n\n\n\n<li><strong>Am\u00e9lioration de l&rsquo;UX et des r\u00e9sultats SEO :<\/strong> le header bidding c\u00f4t\u00e9 serveur aide \u00e0 r\u00e9soudre les probl\u00e8mes de latence.<\/li>\n\n\n\n<li><strong>Plus de donn\u00e9es : <\/strong>le header bidding fournit aux \u00e9diteurs une grande quantit\u00e9 de donn\u00e9es, ce qui les aide \u00e0 prendre des d\u00e9cisions concernant leur site web et leur inventaire.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Limites du Header Bidding<\/h3>\n\n\n\n<p>Bien que le header bidding ait r\u00e9volutionn\u00e9 le monde de la publicit\u00e9 programmatique, il n&rsquo;est pas sans d\u00e9fis.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Technologie :<\/strong> L&rsquo;impl\u00e9mentation du header bidding est plus complexe sur le plan technologique, car chaque SSP, ad exchange ou ad network doit \u00eatre ajout\u00e9 dans le code du site de l&rsquo;\u00e9diteur.<\/li>\n\n\n\n<li><strong>Ench\u00e8res dupliqu\u00e9es :<\/strong> Un annonceur connect\u00e9 \u00e0 plusieurs ad networks peut se retrouver en comp\u00e9tition contre lui-m\u00eame sans le savoir, ce qui peut nuire aux performances et saturer le volume de donn\u00e9es \u00e9chang\u00e9es au sein de l&rsquo;\u00e9cosyst\u00e8me.<\/li>\n\n\n\n<li><strong>D\u00e9fis d&rsquo;identification des utilisateurs :<\/strong> Le header bidding c\u00f4t\u00e9 serveur a souvent du mal \u00e0 faire correspondre les utilisateurs avec pr\u00e9cision, car une grande partie des donn\u00e9es est supprim\u00e9e lors du traitement par le serveur.<\/li>\n\n\n\n<li><strong>Compatibilit\u00e9 des navigateurs : <\/strong>Le header bidding c\u00f4t\u00e9 client fonctionne directement dans le navigateur, ce qui n\u00e9cessite de supporter une grande vari\u00e9t\u00e9 de navigateurs, y compris des versions obsol\u00e8tes. Cela peut entra\u00eener des difficult\u00e9s techniques. De plus, certains navigateurs restreignent ou bloquent les connexions de pixels externes, r\u00e9duisant ainsi l&rsquo;efficacit\u00e9 des ench\u00e8res en header bidding.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; width: 100%;\">\n  <div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-192300748571\"\n    style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"192300748571\">\n    <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLIpZ%2BxKE9%2BHd4i4OZORJYPYjgGwsEcGQZwSl6Ql2OsytBp9sTLp685vI3oC9UsajzL7FEZV0qT0jYK3J4KD9jX2p1VGWsh0tEqCat%2FqxxhvBHT11%2BUlFU3pwHo3JXeFwY0o9pDPhmDG7p2jNJNFkC1OPCOMmLI0aoUTZcElgQ2TWa9PIGTsOq3SCFxvKMq%2FdifGys2Dm%2FzBMuTTIntk1pDi0dybnm4Wme%2FHQbSkhXmuw2Rc6sX2TugZdZFj7XTyJuFr5Seuw%2BvJhhl7j%2F1%2BNr16jVgeB95iErvwTc8bxuzS&#038;webInteractiveContentId=192300748571&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n      <img decoding=\"async\" alt=\"Demo Banner\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-192300748571.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n        onerror=\"this.style.display='none'\" \/>\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Principales Diff\u00e9rences Entre le Header Bidding et le Mod\u00e8le Waterfall :<\/h2>\n\n\n\n<p>Le header bidding et le waterfall bidding diff\u00e8rent consid\u00e9rablement dans leur fonctionnement, ce qui impacte tout, de l&rsquo;optimisation des revenus publicitaires \u00e0 l&rsquo;exp\u00e9rience utilisateur. Voici une analyse des principales distinctions.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Processus d&rsquo;ench\u00e8res :<\/strong> Dans le mod\u00e8le waterfall, les impressions publicitaires sont propos\u00e9es aux sources de demande de mani\u00e8re s\u00e9quentielle, selon un ordre de priorit\u00e9 pr\u00e9d\u00e9fini. \u00c0 l&rsquo;inverse, le header bidding permet \u00e0 tous les partenaires de demande d&rsquo;ench\u00e9rir simultan\u00e9ment, garantissant que l&rsquo;offre la plus \u00e9lev\u00e9e l&#8217;emporte, quel que soit le rang ou les performances pass\u00e9es.<\/li>\n\n\n\n<li><strong>Optimisation des revenus :<\/strong> Le mod\u00e8le waterfall entra\u00eene souvent des pertes de revenus car les impressions peuvent ne pas atteindre l&rsquo;ench\u00e9risseur le plus offrant s&rsquo;il se trouve plus bas dans la cha\u00eene. Le header bidding maximise le potentiel de revenus en favorisant une comp\u00e9tition en temps r\u00e9el entre toutes les sources de demande, garantissant que les impressions soient vendues au plus offrant.<\/li>\n\n\n\n<li><strong>Configuration :<\/strong> Le waterfall bidding est facile \u00e0 mettre en \u0153uvre, ce qui en fait une option accessible pour les petits \u00e9diteurs aux ressources limit\u00e9es. D&rsquo;un autre c\u00f4t\u00e9, le header bidding est plus complexe \u00e0 configurer, n\u00e9cessitant une expertise technique et une int\u00e9gration avec plusieurs partenaires de demande.<\/li>\n\n\n\n<li><strong>Inventaire publicitaire :<\/strong> Le mod\u00e8le waterfall est souvent utilis\u00e9 pour l&rsquo;inventaire remnant qui n&rsquo;a pas \u00e9t\u00e9 vendu via des deals directs. Le header bidding, en revanche, permet aux \u00e9diteurs de mon\u00e9tiser tout leur inventaire, et pas seulement les restes, assurant ainsi un rendement (yield) maximal.<\/li>\n\n\n\n<li><strong>Latence :<\/strong> En raison de sa nature s\u00e9quentielle, le waterfall bidding introduit une latence \u00e9lev\u00e9e \u00e0 mesure que les impressions descendent la cha\u00eene, ce qui affecte n\u00e9gativement les temps de chargement des pages. Le header bidding, en particulier c\u00f4t\u00e9 serveur, r\u00e9duit consid\u00e9rablement la latence en traitant les ench\u00e8res simultan\u00e9ment, ce qui permet un rendu de page plus rapide et une exp\u00e9rience utilisateur plus fluide. C&rsquo;est un point crucial pour maintenir de bons scores <a href=\"https:\/\/developers.google.com\/search\/docs\/appearance\/core-web-vitals\">Google Core Web Vitals<\/a>, notamment le Largest Contentful Paint (LCP) et l&rsquo;Interaction to Next Paint (INP), qui sont des indicateurs cl\u00e9s pour le r\u00e9f\u00e9rencement et la satisfaction des utilisateurs.<\/li>\n\n\n\n<li><strong>Taux de remplissage :<\/strong> Dans le mod\u00e8le waterfall, le taux de remplissage diminue lorsqu&rsquo;aucun partenaire de demande n&rsquo;ach\u00e8te l&rsquo;impression. La concurrence accrue du header bidding se traduit par des taux de remplissage plus \u00e9lev\u00e9s, car davantage de partenaires de demande se disputent le m\u00eame inventaire.<\/li>\n\n\n\n<li><strong>Contr\u00f4le des performances :<\/strong> Le waterfall bidding n&rsquo;offre que peu ou pas de capacit\u00e9 d&rsquo;\u00e9valuation des performances publicitaires, laissant aux \u00e9diteurs des informations minimales. Le header bidding fournit des donn\u00e9es de reporting d\u00e9taill\u00e9es, permettant aux \u00e9diteurs d&rsquo;analyser et d&rsquo;optimiser efficacement leurs performances. De plus, le mod\u00e8le waterfall souffre souvent d&rsquo;\u00e9carts de donn\u00e9es \u00e9lev\u00e9s en raison de l&rsquo;inefficacit\u00e9 du suivi et du reporting. Le header bidding r\u00e9duit consid\u00e9rablement ces \u00e9carts en fournissant des donn\u00e9es plus pr\u00e9cises et en temps r\u00e9el.<\/li>\n\n\n\n<li><strong>Partenaires de demande :<\/strong> Le waterfall bidding est limit\u00e9 \u00e0 un petit nombre de partenaires de demande, ce qui restreint la concurrence et le potentiel de revenus. Le header bidding accueille plusieurs partenaires de demande simultan\u00e9ment, renfor\u00e7ant ainsi la comp\u00e9tition et g\u00e9n\u00e9rant de meilleurs r\u00e9sultats.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Dans le d\u00e9bat opposant le header bidding au waterfall, le premier offre clairement des avantages sur la plupart des aspects, mais le waterfall bidding poss\u00e8de des atouts qui lui sont propres. En comprenant la proposition de valeur distincte de chaque technique, les \u00e9diteurs peuvent d\u00e9cider laquelle correspond le mieux \u00e0 leurs besoins.<\/p>\n\n\n\n<p>\u00c0 mesure que l&rsquo;industrie \u00e9volue du waterfall bidding vers le header bidding et au-del\u00e0, des plateformes comme Opti Digital continuent de stimuler l&rsquo;innovation, en proposant des outils sophistiqu\u00e9s qui aident les \u00e9diteurs \u00e0 maximiser leurs revenus publicitaires tout en offrant une int\u00e9gration transparente et une analyse d\u00e9taill\u00e9e en temps r\u00e9el. <a href=\"https:\/\/optidigital.com\/fr\/contactez-nous\/\">N&rsquo;h\u00e9sitez pas \u00e0 nous contacter<\/a> si vous souhaitez en savoir plus sur les technologies d&rsquo;optimisation des revenus d&rsquo;Opti Digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Header Bidding est devenu un outil indispensable pour les \u00e9diteurs dans l&rsquo;\u00e9cosyst\u00e8me innovant du programmatique, gr\u00e2ce \u00e0 sa capacit\u00e9 \u00e0 maximiser le yield et \u00e0 instaurer une r\u00e9elle comp\u00e9tition sur l&rsquo;inventaire publicitaire. Mais avant l&rsquo;av\u00e8nement du Header Bidding, c&rsquo;est le Waterfall qui dominait le paysage. Dans ce deuxi\u00e8me volet de notre s\u00e9rie, nous explorerons &#8230; <a title=\"Le Header Bidding face au Waterfall\" class=\"read-more\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/\" aria-label=\"En savoir plus sur Le Header Bidding face au Waterfall\">Lire la suite<\/a><\/p>\n","protected":false},"author":11,"featured_media":23949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[394,399,401],"tags":[],"class_list":["post-28784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-monetisation-fr","category-publicite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Header Bidding vs Waterfall | Opti Digital<\/title>\n<meta name=\"description\" content=\"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Header Bidding vs Waterfall | Opti Digital\" \/>\n<meta property=\"og:description\" content=\"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/\" \/>\n<meta property=\"og:site_name\" content=\"Optidigital\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T09:56:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:33:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rub\u00e9n Quinteros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rub\u00e9n Quinteros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/\"},\"author\":{\"name\":\"Rub\u00e9n Quinteros\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/887eb38d7f3943c3fbf191672050991a\"},\"headline\":\"Le Header Bidding face au Waterfall\",\"datePublished\":\"2024-11-20T09:56:35+00:00\",\"dateModified\":\"2026-05-08T09:33:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/\"},\"wordCount\":2641,\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/hb_vs_waterfall_1x.webp\",\"articleSection\":[\"Blog\",\"Mon\u00e9tisation\",\"Publicit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/\",\"name\":\"Header Bidding vs Waterfall | Opti Digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/hb_vs_waterfall_1x.webp\",\"datePublished\":\"2024-11-20T09:56:35+00:00\",\"dateModified\":\"2026-05-08T09:33:11+00:00\",\"description\":\"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/hb_vs_waterfall_1x.webp\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/hb_vs_waterfall_1x.webp\",\"width\":600,\"height\":400,\"caption\":\"Header Bidding vs Waterfall\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/le-header-bidding-face-au-waterfall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Header Bidding face au Waterfall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"name\":\"Optidigital\",\"description\":\"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.\",\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\",\"name\":\"Optidigital\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"width\":169,\"height\":64,\"caption\":\"Optidigital\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/887eb38d7f3943c3fbf191672050991a\",\"name\":\"Rub\u00e9n Quinteros\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/author\\\/ruben\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Header Bidding vs Waterfall | Opti Digital","description":"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/","og_locale":"fr_FR","og_type":"article","og_title":"Header Bidding vs Waterfall | Opti Digital","og_description":"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.","og_url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/","og_site_name":"Optidigital","article_published_time":"2024-11-20T09:56:35+00:00","article_modified_time":"2026-05-08T09:33:11+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","type":"image\/webp"}],"author":"Rub\u00e9n Quinteros","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rub\u00e9n Quinteros","Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#article","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/"},"author":{"name":"Rub\u00e9n Quinteros","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/887eb38d7f3943c3fbf191672050991a"},"headline":"Le Header Bidding face au Waterfall","datePublished":"2024-11-20T09:56:35+00:00","dateModified":"2026-05-08T09:33:11+00:00","mainEntityOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/"},"wordCount":2641,"publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","articleSection":["Blog","Mon\u00e9tisation","Publicit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/","url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/","name":"Header Bidding vs Waterfall | Opti Digital","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#primaryimage"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","datePublished":"2024-11-20T09:56:35+00:00","dateModified":"2026-05-08T09:33:11+00:00","description":"Header bidding vs waterfall : une comparaison claire pour aider les \u00e9diteurs \u00e0 maximiser leurs revenus et \u00e0 mieux exploiter leurs ressources.","breadcrumb":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#primaryimage","url":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","width":600,"height":400,"caption":"Header Bidding vs Waterfall"},{"@type":"BreadcrumbList","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/le-header-bidding-face-au-waterfall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optidigital.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Header Bidding face au Waterfall"}]},{"@type":"WebSite","@id":"https:\/\/optidigital.com\/fr\/#website","url":"https:\/\/optidigital.com\/fr\/","name":"Optidigital","description":"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.","publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optidigital.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optidigital.com\/fr\/#organization","name":"Optidigital","url":"https:\/\/optidigital.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","width":169,"height":64,"caption":"Optidigital"},"image":{"@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/887eb38d7f3943c3fbf191672050991a","name":"Rub\u00e9n Quinteros","url":"https:\/\/optidigital.com\/fr\/author\/ruben\/"}]}},"featured_image_url":"https:\/\/optidigital.com\/wp-content\/uploads\/hb_vs_waterfall_1x.webp","_links":{"self":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/comments?post=28784"}],"version-history":[{"count":4,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28784\/revisions"}],"predecessor-version":[{"id":28799,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28784\/revisions\/28799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media\/23949"}],"wp:attachment":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media?parent=28784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/categories?post=28784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/tags?post=28784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}