{"id":28212,"date":"2024-05-10T12:08:00","date_gmt":"2024-05-10T10:08:00","guid":{"rendered":"http:\/\/optidigital.com\/non-classifiee\/is-attention-the-new-viewability-2\/"},"modified":"2026-02-17T15:44:23","modified_gmt":"2026-02-17T14:44:23","slug":"lattention-est-elle-la-nouvelle-viewability","status":"publish","type":"post","link":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/","title":{"rendered":"L\u2019attention est-elle la nouvelle viewability ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans un paysage AdTech en constante \u00e9volution, les m\u00e9triques d\u2019attention s\u2019imposent comme une solution cl\u00e9 pour les annonceurs souhaitant maximiser l\u2019impact de leurs campagnes publicitaires sans recourir aux cookies tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si les indicateurs traditionnels comme le taux de viewability apportent des informations utiles, ils ne suffisent pas \u00e0 mesurer l\u2019engagement r\u00e9el des utilisateurs avec les publicit\u00e9s. Les solutions de mesure de l\u2019attention vont plus loin : elles offrent une compr\u00e9hension approfondie de la mani\u00e8re dont les utilisateurs interagissent avec les annonces et permettent une analyse plus pr\u00e9cise de l\u2019efficacit\u00e9 des campagnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comment l\u2019attention est-elle mesur\u00e9e ? En quoi diff\u00e8re-t-elle de la viewability ? Pourquoi est-il essentiel pour le march\u00e9 de standardiser ces m\u00e9triques ? Explorons ces questions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">Les m\u00e9triques d\u2019attention : la nouvelle monnaie des annonceurs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreuses donn\u00e9es entrent en jeu lorsqu\u2019il s\u2019agit d\u2019am\u00e9liorer les revenus publicitaires et la performance globale des campagnes. Parmi elles, la <strong>viewability<\/strong>, qui correspond au pourcentage de la surface publicitaire visible \u00e0 l\u2019\u00e9cran pendant une dur\u00e9e donn\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour mieux comprendre la viewability, consultez notre article : <em>Advertising Viewability: Your Best Ally in Boosting Your eCPMs.<\/em>Cependant, la viewability seule ne donne pas une vision compl\u00e8te. Elle ne r\u00e9pond pas r\u00e9ellement \u00e0 la question : <strong>\u00ab<\/strong><a href=\"http:\/\/optidigital.com\/resources\/blog\/advertising-viewability-your-best-ally-in-boosting-your-ecpms\/\"><strong> L\u2019utilisateur a-t-il pr\u00eat\u00e9 attention \u00e0 la publicit\u00e9 ?<\/strong><\/a><strong> \u00bb<\/strong><\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; width: 100%;\">\n  <div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-192302707121\"\n    style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"192302707121\">\n    <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLLsGUaCilYgQ9oUlFQcADRjMc%2BaamcbQwn%2BtbstzUNnHPCkBqUiVZnDBAAsXndQKSvB6cKOujurJEG7xF92%2BjjUqJkCpghYwPBsZT%2B6QK8B2f9pZWygV%2FqPS1rJD801xC9qA%2F8yMvH0RgILCJ1ozBCy0DytMdHdsovjyYWLTnUKvBTGpzCTJATmaI3m10XSZuswa0PI6lLvi1C6Gq6%2Bu%2BGIneMroTDLVielyaNSDhICCA%2FL1QqbMpUo8juAPMjQy0hrHXM%2BcZJyw5MCv3uno9hiXaPf%2B4P2KDpPxAARZp0WPQl8eAgMChYO4SuPvWfnpow%3D&#038;webInteractiveContentId=192302707121&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n      <img decoding=\"async\" alt=\"El Plural\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-192302707121.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n        onerror=\"this.style.display='none'\" \/>\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Une annonce peut \u00eatre visible \u00e0 l\u2019\u00e9cran sans \u00eatre r\u00e9ellement regard\u00e9e, l\u2019utilisateur \u00e9tant concentr\u00e9 sur le contenu \u00e9ditorial. Voir une publicit\u00e9 et interagir avec elle sont deux choses diff\u00e9rentes. La viewability ne permet pas de mesurer l\u2019attention r\u00e9elle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien qu\u2019elle reste un crit\u00e8re d\u2019investissement standard pour les annonceurs, la viewability ne suffit plus \u00e0 garantir le ROI d\u2019une campagne ni \u00e0 \u00e9valuer la qualit\u00e9 d\u2019un inventaire. Les acheteurs se tournent donc de plus en plus vers les m\u00e9triques d\u2019attention, qui r\u00e9v\u00e8lent un niveau d\u2019engagement plus profond que la simple visibilit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">L\u2019attention dans un monde sans cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avec la disparition progressive des cookies tiers (3PC), les annonceurs rencontrent des difficult\u00e9s pour mesurer efficacement la performance publicitaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les m\u00e9triques d\u2019attention apportent une solution adapt\u00e9e \u00e0 l\u2019\u00e8re cookieless. Contrairement aux cookies tiers, des indicateurs tels que :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>le temps d\u2019exposition (dwell time)<\/li>\n\n\n\n<li>les interactions<\/li>\n\n\n\n<li>les mouvements de souris<\/li>\n\n\n\n<li>r\u00e9v\u00e8lent un int\u00e9r\u00eat r\u00e9el et mesurable<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Surtout, elles respectent davantage la vie priv\u00e9e, reposant sur des donn\u00e9es anonymis\u00e9es ou sur le consentement explicite des utilisateurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En combinant les donn\u00e9es d\u2019attention avec le contexte \u00e9ditorial, les annonceurs peuvent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Identifier les environnements \u00e0 fort potentiel d\u2019engagement<\/li>\n\n\n\n<li>Optimiser leur ciblage<\/li>\n\n\n\n<li>Adapter leurs messages en fonction du contenu environnant<\/li>\n<\/ul>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; width: 100%;\">\n  <div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-191509524642\"\n    style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"191509524642\">\n    <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLIFLKRqUMpiQY5xrb53vSQ94lNK69v4tRs2%2FWHuDftqiXesWjmNnR0ThDDdHwTvcUnXPUbmTVPs5PiVvs%2BYghiBkK0GR%2BTEQ9z2uYbwEBeY4lufiQDR4EildxZZM28zZ%2F7GlZ0SeLrMZJCJfE7ezg9mHTEJ4YGT%2F21OCSUQxr57s9ynU7ijLah5St3nIEI7dajq513ZeToJP%2BZJjV63%2FJt36pk8VlUIJTTucKh6f%2BG2xv0zukVOHANCg6EUWQXOgBXLjVb1oPAvKHHHSdI%3D&#038;webInteractiveContentId=191509524642&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n      <img decoding=\"async\" alt=\"Opti Digital | Demand Hub\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-191509524642.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n        onerror=\"this.style.display='none'\" \/>\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">Les diff\u00e9rents indicateurs de mesure de l\u2019attention<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Reconnu par l\u2019IAB, le concept d\u2019attention transforme la mani\u00e8re dont les annonceurs \u00e9valuent l\u2019efficacit\u00e9 publicitaire dans un environnement sans cookies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, mesurer l\u2019attention ne repose pas sur un indicateur unique. Il s\u2019agit d\u2019une analyse fine combinant plusieurs donn\u00e9es issues de panels ou d\u2019utilisateurs :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Heatmaps d\u2019engagement<\/li>\n\n\n\n<li>Survols de souris<\/li>\n\n\n\n<li>Taux de compl\u00e9tion vid\u00e9o<\/li>\n\n\n\n<li>Clics<\/li>\n\n\n\n<li>Conversions post-clic<\/li>\n\n\n\n<li>Densit\u00e9 publicitaire (nombre d\u2019annonces par page)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Eye-tracking et Machine Learning<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une technique puissante consiste \u00e0 utiliser l\u2019eye-tracking, qui analyse les mouvements oculaires. Gr\u00e2ce \u00e0 des mod\u00e8les de Machine Learning appliqu\u00e9s aux donn\u00e9es collect\u00e9es via des panels, les acheteurs peuvent comprendre o\u00f9 se porte r\u00e9ellement l\u2019attention des utilisateurs et optimiser le placement publicitaire en cons\u00e9quence.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">L\u2019approche d\u2019Opti Digital<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Chez Opti Digital, notre format publicitaire propri\u00e9taire capte des signaux en temps r\u00e9el afin de pr\u00e9dire :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le temps pendant lequel une publicit\u00e9 reste visible sur l\u2019\u00e9cran actif<\/li>\n\n\n\n<li>Le niveau d\u2019engagement g\u00e9n\u00e9r\u00e9<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Notre technologie propri\u00e9taire <strong>Demand Hub<\/strong> combine ces donn\u00e9es avec d\u2019autres donn\u00e9es agr\u00e9g\u00e9es afin de segmenter les audiences et d\u2019ench\u00e9rir dynamiquement selon le niveau d\u2019attention pr\u00e9dit, avec une grande pr\u00e9cision.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 ce mod\u00e8le pr\u00e9dictif :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019un taux d\u2019ench\u00e8re plus \u00e9lev\u00e9<\/li>\n\n\n\n<li>Les CPM augmentent sur les emplacements \u00e0 forte attention<\/li>\n\n\n\n<li>Les annonceurs acc\u00e8dent \u00e0 un inventaire premium \u00e0 fort impact<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9sultat : une performance optimis\u00e9e pour l\u2019ensemble de l\u2019\u00e9cosyst\u00e8me.D\u00e9couvrez notre format <a href=\"http:\/\/optidigital.com\/en\/opti-engage\/\">innovant Demand Hub<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">La n\u00e9cessit\u00e9 de standardiser la mesure de l\u2019attention<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 son potentiel, la mesure de l\u2019attention pr\u00e9sente des d\u00e9fis :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Donn\u00e9es fragment\u00e9es provenant de sources multiples<\/li>\n\n\n\n<li>Absence de d\u00e9finition universelle<\/li>\n\n\n\n<li>Complexit\u00e9 d\u2019int\u00e9gration dans les protocoles existants<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Une standardisation, align\u00e9e avec les directives de l\u2019IAB (Interactive Advertising Bureau), est essentielle. Id\u00e9alement, le niveau d\u2019attention devrait \u00eatre transmis dans la bid request via le protocole OpenRTB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La standardisation permettrait :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De distinguer le trafic premium du trafic frauduleux<\/li>\n\n\n\n<li>D\u2019identifier les sous-domaines MFA (Made For Arbitrage)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019\u00e9viter le gaspillage budg\u00e9taire sur des inventaires \u00e0 faible engagement<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">Une \u00e9volution au-del\u00e0 de la viewability<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Selon une \u00e9tude d\u2019EMARKETER publi\u00e9e en janvier 2024, une publicit\u00e9 vue pendant 3 secondes a <strong>50 % plus de chances de g\u00e9n\u00e9rer une conversion<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les m\u00e9triques d\u2019attention repr\u00e9sentent donc l\u2019\u00e9volution naturelle au-del\u00e0 de la viewability :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elles offrent une approche plus pr\u00e9cise et respectueuse de la vie priv\u00e9e<\/li>\n\n\n\n<li>Elles mesurent l\u2019engagement r\u00e9el<\/li>\n\n\n\n<li>Elles sont adapt\u00e9es \u00e0 un monde sans cookies<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Points cl\u00e9s \u00e0 retenir<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019attention red\u00e9finit la publicit\u00e9 digitale en mesurant l\u2019engagement r\u00e9el.<\/li>\n\n\n\n<li>Dans un environnement cookieless, elle devient essentielle pour optimiser le ROI.<\/li>\n\n\n\n<li>Demand Hub d\u2019Opti Digital utilise des analyses pr\u00e9dictives en temps r\u00e9el pour identifier le trafic premium et garantir des CPM plus \u00e9lev\u00e9s.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/optidigital.com\/contact-us\/\">Contactez-nous<\/a> pour en savoir plus sur Demand Hub.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; width: 100%;\">\n  <div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-192300748571\"\n    style=\"max-width:100%; max-height:100%; width:700px;height:180.40625px\" data-hubspot-wrapper-cta-id=\"192300748571\">\n    <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLIpZ%2BxKE9%2BHd4i4OZORJYPYjgGwsEcGQZwSl6Ql2OsytBp9sTLp685vI3oC9UsajzL7FEZV0qT0jYK3J4KD9jX2p1VGWsh0tEqCat%2FqxxhvBHT11%2BUlFU3pwHo3JXeFwY0o9pDPhmDG7p2jNJNFkC1OPCOMmLI0aoUTZcElgQ2TWa9PIGTsOq3SCFxvKMq%2FdifGys2Dm%2FzBMuTTIntk1pDi0dybnm4Wme%2FHQbSkhXmuw2Rc6sX2TugZdZFj7XTyJuFr5Seuw%2BvJhhl7j%2F1%2BNr16jVgeB95iErvwTc8bxuzS&#038;webInteractiveContentId=192300748571&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n      <img decoding=\"async\" alt=\"Demo Banner\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-192300748571.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n        onerror=\"this.style.display='none'\" \/>\n    <\/a>\n  <\/div>\n<\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">FAQs<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1754553105140\"><strong class=\"schema-faq-question\"><strong><strong><strong>Qu\u2019est-ce qu\u2019une m\u00e9trique d\u2019attention en publicit\u00e9 ?<\/strong><\/strong><\/strong><\/strong> <p class=\"schema-faq-answer\">Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el des utilisateurs avec les publicit\u00e9s, au-del\u00e0 des impressions ou de la simple viewability. Elles incluent des indicateurs tels que le temps d\u2019exposition, les mouvements de souris et les interactions.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1754553180800\"><strong class=\"schema-faq-question\"><strong><strong><strong>Quelle est la diff\u00e9rence entre attention et viewability ?<\/strong><\/strong><\/strong><\/strong> <p class=\"schema-faq-answer\">La viewability indique si une publicit\u00e9 \u00e9tait visible \u00e0 l\u2019\u00e9cran. Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el de l\u2019utilisateur, comme la dur\u00e9e d\u2019attention ou les interactions, offrant une vision plus pr\u00e9cise de l\u2019efficacit\u00e9 publicitaire.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1754557066389\"><strong class=\"schema-faq-question\"><strong><strong><strong>Pourquoi standardiser la mesure de l\u2019attention ?<\/strong><\/strong><\/strong><\/strong> <p class=\"schema-faq-answer\">La standardisation garantit une coh\u00e9rence des donn\u00e9es, permet de lutter contre la fraude publicitaire et aide les annonceurs \u00e0 investir dans un inventaire r\u00e9ellement premium, tout en renfor\u00e7ant la transparence entre \u00e9diteurs et annonceurs.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans un paysage AdTech en constante \u00e9volution, les m\u00e9triques d\u2019attention s\u2019imposent comme une solution cl\u00e9 pour les annonceurs souhaitant maximiser l\u2019impact de leurs campagnes publicitaires sans recourir aux cookies tiers. Si les indicateurs traditionnels comme le taux de viewability apportent des informations utiles, ils ne suffisent pas \u00e0 mesurer l\u2019engagement r\u00e9el des utilisateurs avec les &#8230; <a title=\"L\u2019attention est-elle la nouvelle viewability ?\" class=\"read-more\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/\" aria-label=\"En savoir plus sur L\u2019attention est-elle la nouvelle viewability ?\">Lire la suite<\/a><\/p>\n","protected":false},"author":13,"featured_media":28908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[394,612,401],"tags":[],"class_list":["post-28212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-produit","category-publicite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019attention est-elle la nouvelle viewability ?<\/title>\n<meta name=\"description\" content=\"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019attention est-elle la nouvelle viewability ?\" \/>\n<meta property=\"og:description\" content=\"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/\" \/>\n<meta property=\"og:site_name\" content=\"Optidigital\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T10:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T14:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optidigital.com\/wp-content\/uploads\/Is-Attention-The-New-Viewability.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Guillem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/\"},\"author\":{\"name\":\"Guillem\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/7b88d735457d67c5879919c203c57e98\"},\"headline\":\"L\u2019attention est-elle la nouvelle viewability ?\",\"datePublished\":\"2024-05-10T10:08:00+00:00\",\"dateModified\":\"2026-02-17T14:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/\"},\"wordCount\":1128,\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/Unlocking-the-Power-of-Attention-Metrics.png\",\"articleSection\":[\"Blog\",\"Produit\",\"Publicit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/\",\"name\":\"L\u2019attention est-elle la nouvelle viewability ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/Unlocking-the-Power-of-Attention-Metrics.png\",\"datePublished\":\"2024-05-10T10:08:00+00:00\",\"dateModified\":\"2026-02-17T14:44:23+00:00\",\"description\":\"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553105140\"},{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553180800\"},{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754557066389\"}],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/Unlocking-the-Power-of-Attention-Metrics.png\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/Unlocking-the-Power-of-Attention-Metrics.png\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019attention est-elle la nouvelle viewability ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"name\":\"Optidigital\",\"description\":\"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.\",\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#organization\",\"name\":\"Optidigital\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"width\":169,\"height\":64,\"caption\":\"Optidigital\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/#\\\/schema\\\/person\\\/7b88d735457d67c5879919c203c57e98\",\"name\":\"Guillem\",\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/author\\\/guillem\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553105140\",\"position\":1,\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553105140\",\"name\":\"Qu\u2019est-ce qu\u2019une m\u00e9trique d\u2019attention en publicit\u00e9 ?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el des utilisateurs avec les publicit\u00e9s, au-del\u00e0 des impressions ou de la simple viewability. Elles incluent des indicateurs tels que le temps d\u2019exposition, les mouvements de souris et les interactions.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553180800\",\"position\":2,\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754553180800\",\"name\":\"Quelle est la diff\u00e9rence entre attention et viewability ?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La viewability indique si une publicit\u00e9 \u00e9tait visible \u00e0 l\u2019\u00e9cran. Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el de l\u2019utilisateur, comme la dur\u00e9e d\u2019attention ou les interactions, offrant une vision plus pr\u00e9cise de l\u2019efficacit\u00e9 publicitaire.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754557066389\",\"position\":3,\"url\":\"https:\\\/\\\/optidigital.com\\\/fr\\\/ressources\\\/blog\\\/lattention-est-elle-la-nouvelle-viewability\\\/#faq-question-1754557066389\",\"name\":\"Pourquoi standardiser la mesure de l\u2019attention ?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La standardisation garantit une coh\u00e9rence des donn\u00e9es, permet de lutter contre la fraude publicitaire et aide les annonceurs \u00e0 investir dans un inventaire r\u00e9ellement premium, tout en renfor\u00e7ant la transparence entre \u00e9diteurs et annonceurs.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019attention est-elle la nouvelle viewability ?","description":"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019attention est-elle la nouvelle viewability ?","og_description":"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.","og_url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/","og_site_name":"Optidigital","article_published_time":"2024-05-10T10:08:00+00:00","article_modified_time":"2026-02-17T14:44:23+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/optidigital.com\/wp-content\/uploads\/Is-Attention-The-New-Viewability.webp","type":"image\/webp"}],"author":"Guillem","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Guillem","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#article","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/"},"author":{"name":"Guillem","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/7b88d735457d67c5879919c203c57e98"},"headline":"L\u2019attention est-elle la nouvelle viewability ?","datePublished":"2024-05-10T10:08:00+00:00","dateModified":"2026-02-17T14:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/"},"wordCount":1128,"publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/Unlocking-the-Power-of-Attention-Metrics.png","articleSection":["Blog","Produit","Publicit\u00e9"],"inLanguage":"fr-FR"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/","url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/","name":"L\u2019attention est-elle la nouvelle viewability ?","isPartOf":{"@id":"https:\/\/optidigital.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#primaryimage"},"image":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/Unlocking-the-Power-of-Attention-Metrics.png","datePublished":"2024-05-10T10:08:00+00:00","dateModified":"2026-02-17T14:44:23+00:00","description":"Les m\u00e9triques d\u2019attention vont au-del\u00e0 de la visibilit\u00e9 pour mesurer le v\u00e9ritable engagement publicitaire. D\u00e9couvrez comment les annonceurs et les \u00e9diteurs b\u00e9n\u00e9ficient d\u2019une mesure standardis\u00e9e de l\u2019attention.","breadcrumb":{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553105140"},{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553180800"},{"@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754557066389"}],"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#primaryimage","url":"https:\/\/optidigital.com\/wp-content\/uploads\/Unlocking-the-Power-of-Attention-Metrics.png","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/Unlocking-the-Power-of-Attention-Metrics.png","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optidigital.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019attention est-elle la nouvelle viewability ?"}]},{"@type":"WebSite","@id":"https:\/\/optidigital.com\/fr\/#website","url":"https:\/\/optidigital.com\/fr\/","name":"Optidigital","description":"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.","publisher":{"@id":"https:\/\/optidigital.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optidigital.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/optidigital.com\/fr\/#organization","name":"Optidigital","url":"https:\/\/optidigital.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","width":169,"height":64,"caption":"Optidigital"},"image":{"@id":"https:\/\/optidigital.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/optidigital.com\/fr\/#\/schema\/person\/7b88d735457d67c5879919c203c57e98","name":"Guillem","url":"https:\/\/optidigital.com\/fr\/author\/guillem\/"},{"@type":"Question","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553105140","position":1,"url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553105140","name":"Qu\u2019est-ce qu\u2019une m\u00e9trique d\u2019attention en publicit\u00e9 ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el des utilisateurs avec les publicit\u00e9s, au-del\u00e0 des impressions ou de la simple viewability. Elles incluent des indicateurs tels que le temps d\u2019exposition, les mouvements de souris et les interactions.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553180800","position":2,"url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754553180800","name":"Quelle est la diff\u00e9rence entre attention et viewability ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La viewability indique si une publicit\u00e9 \u00e9tait visible \u00e0 l\u2019\u00e9cran. Les m\u00e9triques d\u2019attention mesurent l\u2019engagement r\u00e9el de l\u2019utilisateur, comme la dur\u00e9e d\u2019attention ou les interactions, offrant une vision plus pr\u00e9cise de l\u2019efficacit\u00e9 publicitaire.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754557066389","position":3,"url":"https:\/\/optidigital.com\/fr\/ressources\/blog\/lattention-est-elle-la-nouvelle-viewability\/#faq-question-1754557066389","name":"Pourquoi standardiser la mesure de l\u2019attention ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"La standardisation garantit une coh\u00e9rence des donn\u00e9es, permet de lutter contre la fraude publicitaire et aide les annonceurs \u00e0 investir dans un inventaire r\u00e9ellement premium, tout en renfor\u00e7ant la transparence entre \u00e9diteurs et annonceurs.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/optidigital.com\/wp-content\/uploads\/Unlocking-the-Power-of-Attention-Metrics.png","_links":{"self":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/comments?post=28212"}],"version-history":[{"count":1,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28212\/revisions"}],"predecessor-version":[{"id":28214,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/posts\/28212\/revisions\/28214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media\/28908"}],"wp:attachment":[{"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/media?parent=28212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/categories?post=28212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optidigital.com\/fr\/wp-json\/wp\/v2\/tags?post=28212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}