{"id":2797,"date":"2020-01-23T10:43:00","date_gmt":"2020-01-23T09:43:00","guid":{"rendered":"http:\/\/optidigital.com\/?p=2797"},"modified":"2025-05-05T16:10:57","modified_gmt":"2025-05-05T14:10:57","slug":"opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales","status":"publish","type":"post","link":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/","title":{"rendered":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales"},"content":{"rendered":"\n<p><strong>\u00bfTe imaginas poder hacer tests f\u00e1cilmente para conocer los factores que aumentan tus ingresos publicitarios? Opti Digital lanza su soluci\u00f3n de test A\/B que permite tomar decisiones de monetizaci\u00f3n con agilidad. La empresa presentar\u00e1 esta soluci\u00f3n en los Encuentros de Editores Ratecard que se celebrar\u00e1n los d\u00edas 29 y 30 del pr\u00f3ximo enero en Barcelona.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El test A\/B aplicado a la monetizaci\u00f3n: una innovaci\u00f3n Opti Digital<\/strong><\/h2>\n\n\n\n<p>Conocemos los tests A\/B destinados a mejorar el t\u00fanel de conversi\u00f3n de las p\u00e1ginas webs comerciales, los tests A\/B y los tests multivariables destinados a mejorar la tasa de contactos o <em>leads<\/em> de una <em>landing page<\/em> mediante soluciones orientadas a los anunciantes como Google Website Optimizer. Opti Digital innova y aplica el principio del test A\/B a la monetizaci\u00f3n publicitaria. <strong>La herramienta permite mostrar dos configuraciones distintas en paralelo a dos grupos de internautas, durante un mismo periodo, y analizar los <a href=\"https:\/\/optidigital.com\/es\/dashboard-publisher\/\">KPI o indicadores clave de monetizaci\u00f3n<\/a>.<\/strong><\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-174197273397\"\n  style=\"max-width:100%; max-height:100%; width:650px;height:162.5px\" data-hubspot-wrapper-cta-id=\"174197273397\">\n  <a href=\"https:\/\/cta-service-cms2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLLGFqhS8aYCehdXkUZhehQ5aXxSosfRXHT99ISsaPZfSJ%2FiZRYqVAcaTQkI%2FdklnXeOeNwsu01QyDR%2BtGin0Jag%2FLSNG7%2Byci2gIfk7CJTCHDvLpAk4xl3cnDBBldoW98QxAmRybaTqrK16L2STZ2GRI2F7Cr5M3pKnNM1sohl9RDz%2FWmU6vbp0Jn9sxI%2F3M4NStGTKWx73Nh1eGoZigjf3pe6DuJwSoIuGmT5g7q0%2F0xEjG9NWb8inqCXDuV%2BOf8fOtj3UXA9786rkH9oo&#038;webInteractiveContentId=174197273397&#038;portalId=4547509\" target=\"_blank\" rel=\"noopener\" crossorigin=\"anonymous\">\n    <img decoding=\"async\" alt=\"2-2\" loading=\"lazy\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/4547509\/interactive-174197273397.png\" style=\"height: 100%; width: 100%; object-fit: fill\"\n      onerror=\"this.style.display='none'\" \/>\n  <\/a>\n<\/div>\n\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ejemplo de test A\/B: Ajuste del floor price de un emplazamiento m\u00f3vil<\/strong><\/h2>\n\n\n\n<p>Para ilustrar la soluci\u00f3n de test A\/B de Opti Digital, hemos estudiado el caso de una p\u00e1gina web de viajes en la audiencia m\u00f3vil, entre el 16 y el 22 de enero de 2020 en Francia.&nbsp; (Consulta la captura de pantalla m\u00e1s arriba). El inventario del editor est\u00e1 dividido en dos grupos: un grupo de control y un grupo de test. Podemos definir f\u00e1cilmente el porcentaje de tr\u00e1fico enviado al grupo de test. Cuanto m\u00e1s elevado sea este porcentaje, mayor ser\u00e1 el n\u00famero de datos fiables que obtendremos r\u00e1pidamente y que nos permitir\u00e1n tomar una decisi\u00f3n.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>En el grupo de control, se ha configurado un precio de base m\u00ednimo de 0,20 \u20ac de CPM.<\/li>\n\n\n\n<li>En el grupo de test, se ha aplicado un precio de base m\u00e1s provocador de 1\u00a0\u20ac de CPM en uno de los emplazamientos publicitarios m\u00f3viles.<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s, todos los dem\u00e1s factores se mantienen iguales: los <a href=\"https:\/\/optidigital.com\/es\/codigos-smart\">porcentajes de visibilidad<\/a> se optimizan gracias a los c\u00f3digos smart desarrollados por Opti Digital. Este recurso tecnol\u00f3gico mejora la calidad del inventario: visibilidad, protecci\u00f3n contra los anunciantes malintencionados, comportamiento adaptado, velocidad de carga&#8230; Los socios <a href=\"https:\/\/optidigital.com\/es\/pujas-dinamicas\/\">vendedores program\u00e1ticos compitiendo en el <em>header bidding<\/em><\/a> son los mismos (Prebid.js y Amazon).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El an\u00e1lisis de los resultados del test A\/B<\/strong><\/h2>\n\n\n\n<p>En este ejemplo, el CPM efectivo por impresi\u00f3n es mejor en el grupo de test. Lo que podr\u00eda llevarnos a pensar que esta versi\u00f3n es la m\u00e1s rentable. Pero, <strong>si aplicamos un precio de base m\u00e1s elevado, aumentamos la parte de inventario no vendido y el n\u00famero de impresiones por p\u00e1gina disminuye<\/strong>. La consecuencia de esto es una ligera disminuci\u00f3n del RPM de p\u00e1gina neto, el ingreso neto del editor por cada mil visitas de p\u00e1ginas, el KPI definitivo m\u00e1s importante. Lo que nos demuestra que la versi\u00f3n de test es menos rentable que la versi\u00f3n de control. El precio de base de CPM de 1&nbsp;\u20ac es demasiado elevado.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Utilizamos la soluci\u00f3n de test A\/B cuando queremos interesar a un nuevo vendedor o confirmar una idea de optimizaci\u00f3n. Algunos editores nos transmiten igualmente ideas de tests y nos contactan para implementarlas. Esta herramienta nos permite desarrollar el test y analizar los datos fiables con rapidez.\u00a0<\/strong><\/p>\n<cite><strong>&nbsp;S\u00e9bastien Moutte, Presidente de Opti Digital.<\/strong><\/cite><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ideas de tests A\/B para mejorar la monetizaci\u00f3n publicitaria&nbsp;<\/strong><\/h2>\n\n\n\n<p>Aqu\u00ed tienes algunas ideas de tests A\/B que puedes implementar en tu p\u00e1gina web:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estilo nativo Google \/ Estilo nativo adaptado al dise\u00f1o de la p\u00e1gina web en CSS<\/li>\n\n\n\n<li>A\u00f1adir \/ Suprimir un socio vendedor<\/li>\n\n\n\n<li>Alargar \/ Acortar los tiempos l\u00edmites del <em>header bidding<\/em><\/li>\n\n\n\n<li>A\u00f1adir \/ Suprimir un emplazamiento publicitario<\/li>\n\n\n\n<li>Enfrentar al <em>megabanner<\/em> y al <em>skin<\/em> publicitario \/ Mantener un <em>leaderboard<\/em> cuando se muestra un <em>skin<\/em> publicitario\u00a0<\/li>\n\n\n\n<li>A\u00f1adir \/ Retirar algunos tama\u00f1os de un emplazamiento<\/li>\n\n\n\n<li>Con \/ Sin la soluci\u00f3n de inserci\u00f3n autom\u00e1tica de anuncios en el contenido de Opti Digital<\/li>\n\n\n\n<li>Un proveedor de CMP \/ Otro<\/li>\n\n\n\n<li>Ajustar el dise\u00f1o y la UX del CMP<\/li>\n<\/ul>\n\n\n\n<p><strong>M\u00e1s informaci\u00f3n&nbsp;<\/strong><\/p>\n\n\n\n<p>\u00a1S\u00e9 creativo! Env\u00edanos tus ideas de tests A\/B y juntos pensaremos c\u00f3mo podemos implementarlas en tu p\u00e1gina web.&nbsp;<a href=\"https:\/\/optidigital.com\/es\/contacto\">Contacta con nosotros<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTe imaginas poder hacer tests f\u00e1cilmente para conocer los factores que aumentan tus ingresos publicitarios? Opti Digital lanza su soluci\u00f3n de test A\/B que permite tomar decisiones de monetizaci\u00f3n con agilidad. La empresa presentar\u00e1 esta soluci\u00f3n en los Encuentros de Editores Ratecard que se celebrar\u00e1n los d\u00edas 29 y 30 del pr\u00f3ximo enero en Barcelona. &#8230; <a title=\"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales\" class=\"read-more\" href=\"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/\" aria-label=\"Leer m\u00e1s sobre Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":13,"featured_media":24127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[588,608,508],"tags":[],"class_list":["post-2797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-monetizacion","category-publicidad-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales - Optidigital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales - Optidigital\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe imaginas poder hacer tests f\u00e1cilmente para conocer los factores que aumentan tus ingresos publicitarios? Opti Digital lanza su soluci\u00f3n de test A\/B que permite tomar decisiones de monetizaci\u00f3n con agilidad. La empresa presentar\u00e1 esta soluci\u00f3n en los Encuentros de Editores Ratecard que se celebrar\u00e1n los d\u00edas 29 y 30 del pr\u00f3ximo enero en Barcelona. ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/\" \/>\n<meta property=\"og:site_name\" content=\"Optidigital\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-23T09:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T14:10:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Guillem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/optidigital.com\/wp-content\/uploads\/2020\/02\/img_Etude-Revenues_tw.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/\"},\"author\":{\"name\":\"Guillem\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#\\\/schema\\\/person\\\/7b88d735457d67c5879919c203c57e98\"},\"headline\":\"Opti Digital lanza su soluci\u00f3n de test A\\\/B para la monetizaci\u00f3n de los medios digitales\",\"datePublished\":\"2020-01-23T09:43:00+00:00\",\"dateModified\":\"2025-05-05T14:10:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/\"},\"wordCount\":758,\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp\",\"articleSection\":[\"Blog\",\"Monetizaci\u00f3n\",\"Publicidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/\",\"name\":\"Opti Digital lanza su soluci\u00f3n de test A\\\/B para la monetizaci\u00f3n de los medios digitales - Optidigital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp\",\"datePublished\":\"2020-01-23T09:43:00+00:00\",\"dateModified\":\"2025-05-05T14:10:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp\",\"width\":600,\"height\":400,\"caption\":\"Optimize Media Revenue: Opti Digital Launches A\\\/B Testing Solution\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/recursos\\\/blog\\\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optidigital.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opti Digital lanza su soluci\u00f3n de test A\\\/B para la monetizaci\u00f3n de los medios digitales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/optidigital.com\\\/es\\\/\",\"name\":\"Optidigital\",\"description\":\"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.\",\"publisher\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optidigital.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#organization\",\"name\":\"Optidigital\",\"url\":\"https:\\\/\\\/optidigital.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"contentUrl\":\"https:\\\/\\\/optidigital.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo_w.svg\",\"width\":169,\"height\":64,\"caption\":\"Optidigital\"},\"image\":{\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optidigital.com\\\/es\\\/#\\\/schema\\\/person\\\/7b88d735457d67c5879919c203c57e98\",\"name\":\"Guillem\",\"url\":\"https:\\\/\\\/optidigital.com\\\/es\\\/author\\\/guillem\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales - Optidigital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/","og_locale":"es_ES","og_type":"article","og_title":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales - Optidigital","og_description":"\u00bfTe imaginas poder hacer tests f\u00e1cilmente para conocer los factores que aumentan tus ingresos publicitarios? Opti Digital lanza su soluci\u00f3n de test A\/B que permite tomar decisiones de monetizaci\u00f3n con agilidad. La empresa presentar\u00e1 esta soluci\u00f3n en los Encuentros de Editores Ratecard que se celebrar\u00e1n los d\u00edas 29 y 30 del pr\u00f3ximo enero en Barcelona. ... Leer m\u00e1s","og_url":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/","og_site_name":"Optidigital","article_published_time":"2020-01-23T09:43:00+00:00","article_modified_time":"2025-05-05T14:10:57+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","type":"image\/webp"}],"author":"Guillem","twitter_card":"summary_large_image","twitter_image":"http:\/\/optidigital.com\/wp-content\/uploads\/2020\/02\/img_Etude-Revenues_tw.jpg","twitter_misc":{"Escrito por":"Guillem","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#article","isPartOf":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/"},"author":{"name":"Guillem","@id":"https:\/\/optidigital.com\/es\/#\/schema\/person\/7b88d735457d67c5879919c203c57e98"},"headline":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales","datePublished":"2020-01-23T09:43:00+00:00","dateModified":"2025-05-05T14:10:57+00:00","mainEntityOfPage":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/"},"wordCount":758,"publisher":{"@id":"https:\/\/optidigital.com\/es\/#organization"},"image":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","articleSection":["Blog","Monetizaci\u00f3n","Publicidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/","url":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/","name":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales - Optidigital","isPartOf":{"@id":"https:\/\/optidigital.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#primaryimage"},"image":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#primaryimage"},"thumbnailUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","datePublished":"2020-01-23T09:43:00+00:00","dateModified":"2025-05-05T14:10:57+00:00","breadcrumb":{"@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#primaryimage","url":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","width":600,"height":400,"caption":"Optimize Media Revenue: Opti Digital Launches A\/B Testing Solution"},{"@type":"BreadcrumbList","@id":"https:\/\/optidigital.com\/es\/recursos\/blog\/opti-digital-lanza-su-solucion-de-test-a-b-para-la-monetizacion-de-los-medios-digitales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optidigital.com\/es\/"},{"@type":"ListItem","position":2,"name":"Opti Digital lanza su soluci\u00f3n de test A\/B para la monetizaci\u00f3n de los medios digitales"}]},{"@type":"WebSite","@id":"https:\/\/optidigital.com\/es\/#website","url":"https:\/\/optidigital.com\/es\/","name":"Optidigital","description":"Premium ad revenue platform, built for publishers seeking to optimize their ad revenue while preserving their user experience.","publisher":{"@id":"https:\/\/optidigital.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optidigital.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/optidigital.com\/es\/#organization","name":"Optidigital","url":"https:\/\/optidigital.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/optidigital.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","contentUrl":"https:\/\/optidigital.com\/wp-content\/uploads\/2025\/01\/logo_w.svg","width":169,"height":64,"caption":"Optidigital"},"image":{"@id":"https:\/\/optidigital.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/optidigital.com\/es\/#\/schema\/person\/7b88d735457d67c5879919c203c57e98","name":"Guillem","url":"https:\/\/optidigital.com\/es\/author\/guillem\/"}]}},"featured_image_url":"https:\/\/optidigital.com\/wp-content\/uploads\/optimize_media_revenue_opti_digital_launches_a_b_testing_solution_1x.webp","_links":{"self":[{"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/posts\/2797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":1,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/posts\/2797\/revisions"}],"predecessor-version":[{"id":23620,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/posts\/2797\/revisions\/23620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/media\/24127"}],"wp:attachment":[{"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/categories?post=2797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optidigital.com\/es\/wp-json\/wp\/v2\/tags?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}